{"id":32694,"date":"2020-05-19T01:06:04","date_gmt":"2020-05-19T01:06:04","guid":{"rendered":"https:\/\/www.ccof.org\/covid-19-update-and-best-practices-from-the-aca-and-ioia\/"},"modified":"2024-07-24T16:49:02","modified_gmt":"2024-07-24T16:49:02","slug":"covid-19-update-and-best-practices-from-the-aca-and-ioia","status":"publish","type":"post","link":"https:\/\/www.ccof.org\/es\/news\/covid-19-update-and-best-practices-from-the-aca-and-ioia\/","title":{"rendered":"COVID-19 Actualizaci\u00f3n y mejores pr\u00e1cticas de la ACA y la IOIA"},"content":{"rendered":"<p>A medida que el brote de la Enfermedad del Nuevo Coronavirus 2019 (COVID-19) contin\u00faa creando restricciones de viaje que pueden impactar la certificaci\u00f3n org\u00e1nica, la Asociaci\u00f3n de Certificadores Acreditados (ACA) y la Asociaci\u00f3n Internacional de Inspectores Org\u00e1nicos (IOIA) publican hoy un plan de contingencia pand\u00e9mico para toda la industria, Planes de Contingencia para Verificar el Cumplimiento cuando las Inspecciones In Situ no son Posibles. Este documento de \"Buenas Pr\u00e1cticas\", que se puede encontrar en el\u00a0<a       href=\"https:\/\/www.accreditedcertifiers.org\/wp-content\/uploads\/2020\/05\/ACA-Best-Practices-for-Inspection-Contingency-Plans-05.2020.pdf\">Sitio web del ACA<\/a>es el resultado de la colaboraci\u00f3n de m\u00e1s de 125 participantes, que representan a certificadores org\u00e1nicos, inspectores org\u00e1nicos independientes y otras partes interesadas.<\/p>\n<p>La principal preocupaci\u00f3n de la ACA y de la IOIA es la salud y la seguridad de nuestro personal, de los inspectores, de las personas que trabajan en las operaciones que certificamos y de sus familias. Tambi\u00e9n somos conscientes de que los consumidores que buscan alimentos org\u00e1nicos dependen de nosotros para seguir confiando en la integridad de la etiqueta org\u00e1nica. Afortunadamente, existen muchas herramientas, basadas en textos normativos y orientaciones, que podemos utilizar para verificar el cumplimiento org\u00e1nico mientras existan restricciones de viaje y no sea posible realizar inspecciones in situ. Las Buenas Pr\u00e1cticas que hemos desarrollado se basan en el pensamiento cr\u00edtico para desarrollar un conjunto de directrices generales, herramientas y pr\u00e1cticas que sean coherentes y cre\u00edbles, a la vez que flexibles para permitir a los certificadores, inspectores y operaciones utilizar el pensamiento cr\u00edtico caso por caso para desarrollar y documentar los aspectos espec\u00edficos para cada situaci\u00f3n.<\/p>\n<p>Nuestras recomendaciones generales incluyen:<\/p>\n<ul>\n<li>Los certificadores deben utilizar una evaluaci\u00f3n basada en el riesgo para determinar qu\u00e9 combinaci\u00f3n de inspecci\u00f3n remota y auditor\u00eda de registros debe utilizarse para verificar el cumplimiento de cada operaci\u00f3n existente (ya certificada). Cuando sea posible realizar inspecciones in situ, los certificadores tambi\u00e9n deber\u00e1n utilizar un enfoque basado en el riesgo para establecer prioridades.<\/li>\n<li>Para las operaciones existentes que pretendan a\u00f1adir nuevos productos, terrenos o instalaciones, los certificadores deben evaluar si una inspecci\u00f3n a distancia puede ser suficiente para evaluar el cumplimiento.\u00a0\u00a0<\/li>\n<li>Las nuevas solicitudes de certificaci\u00f3n deben tener prioridad para las inspecciones in situ una vez que sean posibles, ya que las nuevas operaciones no pueden obtener la certificaci\u00f3n inicial sin una inspecci\u00f3n in situ.\u00a0<\/li>\n<li>Se insta a los certificadores acreditados a que se comuniquen peri\u00f3dicamente con sus clientes, incluso compartiendo directamente el plan de contingencia para las inspecciones. 2\u00a0<\/li>\n<li>Los certificadores, inspectores y operaciones deben seguir estando preparados para la inspecci\u00f3n y mantener una buena documentaci\u00f3n de sus procedimientos.<\/li>\n<\/ul>\n<p>El documento de Buenas Pr\u00e1cticas tambi\u00e9n incluye recursos para los ACA y los inspectores, entre ellos:<\/p>\n<ul>\n<li>Recomendaciones espec\u00edficas sobre c\u00f3mo debe realizarse una inspecci\u00f3n a distancia o una auditor\u00eda documental, incluidas opciones para operaciones con acceso limitado a la tecnolog\u00eda.<\/li>\n<li>Oportunidades para apoyar a los inspectores - que son una pieza fundamental de la comunidad org\u00e1nica y cuyo sustento se ve dram\u00e1ticamente afectado por la imposibilidad de realizar inspecciones in situ durante esta pandemia.<\/li>\n<\/ul>\n<p>A medida que la pandemia de COVID-19 siga desarroll\u00e1ndose, supervisaremos y evaluaremos el estado de las inspecciones org\u00e1nicas y la aplicaci\u00f3n de estas Buenas Pr\u00e1cticas.<\/p>\n<p>Reconocemos que este sigue siendo un momento desafiante y sin precedentes con condiciones en constante cambio. Los productores org\u00e1nicos certificados y las operaciones en el proceso de solicitar la certificaci\u00f3n deben ponerse en contacto directamente con su certificador acreditado con cualquier pregunta sobre los efectos de COVID-19 en su proceso de certificaci\u00f3n org\u00e1nica.<\/p>\n<p>Esperamos que usted, sus empleados y sus familias se mantengan sanos y salvos. La salud y la seguridad de nuestra comunidad org\u00e1nica siguen estando en el centro de toda toma de decisiones.<\/p>\n<p>Animamos a todos a que sigan los recursos de la OMS y los CDC para obtener los anuncios y la informaci\u00f3n m\u00e1s actualizados sobre el virus:<\/p>\n<p><a       href=\"https:\/\/www.who.int\/emergencies\/diseases\/novel-coronavirus-2019\">https:\/\/www.who.int\/emergencies\/diseases\/novel-coronavirus-2019<\/a><br       \/><br \/>\n       <a       href=\"https:\/\/www.who.int\/health-topics\/coronavirus#tab=tab_1\">https:\/\/www.who.int\/health-topics\/coronavirus#tab=tab_1<\/a><br       \/><br \/>\n       <a       href=\"https:\/\/www.cdc.gov\/coronavirus\/2019-ncov\/index.html\">https:\/\/www.cdc.gov\/coronavirus\/2019-ncov\/index.html<\/a><br       \/><br \/>\n       <a       href=\"https:\/\/www.cdc.gov\/coronavirus\/2019-ncov\/community\/index.html\">https:\/\/www.cdc.gov\/coronavirus\/2019-ncov\/community\/index.html<\/a><\/p>\n<p><em>Este art\u00edculo se public\u00f3 originalmente como\u00a0<a       href=\"https:\/\/www.ioia.net\/images\/PDF\/2020.05.14_ACA%20Press%20Release.pdf\">comunicado de prensa de la Accredited Certifiers Association, Inc. y la International Organic Inspectors Association<\/a>.<\/em><\/p>\n<p><em>Acerca de Accredited Certifiers Association, Inc.\u00a0 \u00a0       \u00a0<\/em><\/p>\n<p><em>La Accredited Certifiers Association, Inc. (ACA) es una organizaci\u00f3n educativa sin \u00e1nimo de lucro 501(c)(3) creada para beneficiar a la comunidad de certificadores org\u00e1nicos acreditados y a la industria org\u00e1nica. Imaginamos un mundo en el que la etiqueta USDA Organic sea siempre de confianza y valorada. Nuestra misi\u00f3n principal es asegurar la implementaci\u00f3n consistente de las Regulaciones Org\u00e1nicas del USDA a trav\u00e9s de la colaboraci\u00f3n y educaci\u00f3n de las agencias certificadoras acreditadas. Los prop\u00f3sitos incluyen el desarrollo de criterios uniformes para la implementaci\u00f3n del Programa Org\u00e1nico Nacional del USDA, la capacitaci\u00f3n de certificadores, el apoyo y las oportunidades de trabajo en red y ser un foro para la discusi\u00f3n de temas que impactan la certificaci\u00f3n org\u00e1nica.\u00a0 \u00a0<\/em><\/p>\n<p><em>Acerca de la Asociaci\u00f3n Internacional de Inspectores Org\u00e1nicos\u00a0       \u00a0<\/em><\/p>\n<p><em>La Asociaci\u00f3n Internacional de Inspectores Org\u00e1nicos (IOIA) es la organizaci\u00f3n profesional de inspectores org\u00e1nicos y ofrece formaci\u00f3n y contactos en todo el mundo para inspectores de cultivos, ganado y procesado. Constituida en EE.UU. como organizaci\u00f3n sin \u00e1nimo de lucro, la IOIA opera a nivel mundial con cerca de 250 inspectores miembros en m\u00e1s de una docena de pa\u00edses. La afiliaci\u00f3n de apoyo est\u00e1 abierta a particulares, empresas y organizaciones que apoyen los objetivos de la IOIA.\u00a0<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Mientras el brote de la nueva enfermedad por coronavirus 2019 (COVID-19) sigue creando restricciones de viaje ...<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[112],"class_list":["post-32694","post","type-post","status-publish","format-standard","hentry","category-certification-news","language-english","certifications-usda-nop","certification_topics-other-services"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COVID-19 Update and Best Practices from the ACA and IOIA - CCOF.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccof.org\/news\/covid-19-update-and-best-practices-from-the-aca-and-ioia\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COVID-19 Update and Best Practices from the ACA and IOIA - CCOF.org\" \/>\n<meta property=\"og:description\" content=\"As the Novel Coronavirus Disease 2019 (COVID-19) outbreak continues to create travel restrictions &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccof.org\/news\/covid-19-update-and-best-practices-from-the-aca-and-ioia\/\" \/>\n<meta property=\"og:site_name\" content=\"CCOF.org\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CCOForganic\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-19T01:06:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-24T16:49:02+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ccof.org\\\/news\\\/covid-19-update-and-best-practices-from-the-aca-and-ioia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccof.org\\\/news\\\/covid-19-update-and-best-practices-from-the-aca-and-ioia\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/person\\\/5ccd134e7ab95678db6afcb521a44e07\"},\"headline\":\"COVID-19 Update and Best Practices from the ACA and IOIA\",\"datePublished\":\"2020-05-19T01:06:04+00:00\",\"dateModified\":\"2024-07-24T16:49:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ccof.org\\\/news\\\/covid-19-update-and-best-practices-from-the-aca-and-ioia\\\/\"},\"wordCount\":741,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\"},\"articleSection\":[\"Certification News\"],\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ccof.org\\\/news\\\/covid-19-update-and-best-practices-from-the-aca-and-ioia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ccof.org\\\/news\\\/covid-19-update-and-best-practices-from-the-aca-and-ioia\\\/\",\"url\":\"https:\\\/\\\/ccof.org\\\/news\\\/covid-19-update-and-best-practices-from-the-aca-and-ioia\\\/\",\"name\":\"COVID-19 Update and Best Practices from the ACA and IOIA - CCOF.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#website\"},\"datePublished\":\"2020-05-19T01:06:04+00:00\",\"dateModified\":\"2024-07-24T16:49:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ccof.org\\\/news\\\/covid-19-update-and-best-practices-from-the-aca-and-ioia\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ccof.org\\\/news\\\/covid-19-update-and-best-practices-from-the-aca-and-ioia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ccof.org\\\/news\\\/covid-19-update-and-best-practices-from-the-aca-and-ioia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ccof.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COVID-19 Update and Best Practices from the ACA and IOIA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#website\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/\",\"name\":\"CCOF.org\",\"description\":\"Help make organic the norm!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ccof.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\",\"name\":\"CCOF.org\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/ccof-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.ccof.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/ccof-logo.svg\",\"width\":85,\"height\":111,\"caption\":\"CCOF.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CCOForganic\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CCOForganic\",\"https:\\\/\\\/www.instagram.com\\\/ccoforganic\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/person\\\/5ccd134e7ab95678db6afcb521a44e07\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/www.ccof.org\\\/wp\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COVID-19 Actualizaci\u00f3n y buenas pr\u00e1cticas de la ACA y la IOIA - CCOF.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccof.org\/news\/covid-19-update-and-best-practices-from-the-aca-and-ioia\/","og_locale":"es_MX","og_type":"article","og_title":"COVID-19 Update and Best Practices from the ACA and IOIA - CCOF.org","og_description":"As the Novel Coronavirus Disease 2019 (COVID-19) outbreak continues to create travel restrictions &hellip;","og_url":"https:\/\/ccof.org\/news\/covid-19-update-and-best-practices-from-the-aca-and-ioia\/","og_site_name":"CCOF.org","article_publisher":"https:\/\/www.facebook.com\/CCOForganic","article_published_time":"2020-05-19T01:06:04+00:00","article_modified_time":"2024-07-24T16:49:02+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ccof.org\/news\/covid-19-update-and-best-practices-from-the-aca-and-ioia\/#article","isPartOf":{"@id":"https:\/\/ccof.org\/news\/covid-19-update-and-best-practices-from-the-aca-and-ioia\/"},"author":{"name":"admin","@id":"https:\/\/www.ccof.org\/#\/schema\/person\/5ccd134e7ab95678db6afcb521a44e07"},"headline":"COVID-19 Update and Best Practices from the ACA and IOIA","datePublished":"2020-05-19T01:06:04+00:00","dateModified":"2024-07-24T16:49:02+00:00","mainEntityOfPage":{"@id":"https:\/\/ccof.org\/news\/covid-19-update-and-best-practices-from-the-aca-and-ioia\/"},"wordCount":741,"commentCount":0,"publisher":{"@id":"https:\/\/www.ccof.org\/#organization"},"articleSection":["Certification News"],"inLanguage":"es-MX","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ccof.org\/news\/covid-19-update-and-best-practices-from-the-aca-and-ioia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ccof.org\/news\/covid-19-update-and-best-practices-from-the-aca-and-ioia\/","url":"https:\/\/ccof.org\/news\/covid-19-update-and-best-practices-from-the-aca-and-ioia\/","name":"COVID-19 Actualizaci\u00f3n y buenas pr\u00e1cticas de la ACA y la IOIA - CCOF.org","isPartOf":{"@id":"https:\/\/www.ccof.org\/#website"},"datePublished":"2020-05-19T01:06:04+00:00","dateModified":"2024-07-24T16:49:02+00:00","breadcrumb":{"@id":"https:\/\/ccof.org\/news\/covid-19-update-and-best-practices-from-the-aca-and-ioia\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccof.org\/news\/covid-19-update-and-best-practices-from-the-aca-and-ioia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ccof.org\/news\/covid-19-update-and-best-practices-from-the-aca-and-ioia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ccof.org\/"},{"@type":"ListItem","position":2,"name":"COVID-19 Update and Best Practices from the ACA and IOIA"}]},{"@type":"WebSite","@id":"https:\/\/www.ccof.org\/#website","url":"https:\/\/www.ccof.org\/","name":"CCOF.org","description":"\u00a1Ayude a que lo org\u00e1nico sea la norma!","publisher":{"@id":"https:\/\/www.ccof.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ccof.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.ccof.org\/#organization","name":"CCOF.org","url":"https:\/\/www.ccof.org\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.ccof.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.ccof.org\/wp-content\/uploads\/2024\/02\/ccof-logo.svg","contentUrl":"https:\/\/www.ccof.org\/wp-content\/uploads\/2024\/02\/ccof-logo.svg","width":85,"height":111,"caption":"CCOF.org"},"image":{"@id":"https:\/\/www.ccof.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CCOForganic","https:\/\/www.youtube.com\/c\/CCOForganic","https:\/\/www.instagram.com\/ccoforganic\/"]},{"@type":"Person","@id":"https:\/\/www.ccof.org\/#\/schema\/person\/5ccd134e7ab95678db6afcb521a44e07","name":"admin","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/www.ccof.org\/wp"]}]}},"_links":{"self":[{"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/posts\/32694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/comments?post=32694"}],"version-history":[{"count":3,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/posts\/32694\/revisions"}],"predecessor-version":[{"id":47554,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/posts\/32694\/revisions\/47554"}],"wp:attachment":[{"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/media?parent=32694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/categories?post=32694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}