{"id":32817,"date":"2012-12-11T22:08:25","date_gmt":"2012-12-11T22:08:25","guid":{"rendered":"https:\/\/www.ccof.org\/updates-to-national-list-of-allowed-and-prohibited-substances\/"},"modified":"2025-08-12T19:30:36","modified_gmt":"2025-08-12T19:30:36","slug":"updates-to-national-list-of-allowed-and-prohibited-substances","status":"publish","type":"post","link":"https:\/\/www.ccof.org\/es\/news\/updates-to-national-list-of-allowed-and-prohibited-substances\/","title":{"rendered":"Actualizaciones de la lista nacional de sustancias permitidas y prohibidas"},"content":{"rendered":"<div class=\"field field-name-body field-type-text-with-summary field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>A principios de este a\u00f1o, el Programa Nacional Org\u00e1nico public\u00f3 una norma final que renovaba m\u00e1s de 200 sustancias de la Lista Nacional de Sustancias Permitidas y Prohibidas que estaban programadas para expirar este a\u00f1o. La norma tambi\u00e9n introdujo cambios en las sustancias que se indican a continuaci\u00f3n. CCOF ha contactado directamente a los clientes afectados; sin embargo, si usted utiliza cualquiera de los materiales indicados a continuaci\u00f3n y tiene preguntas adicionales, por favor <a href=\"mailto:ccof@ccof.org\" target=\"_blank\" rel=\"noopener\">cont\u00e1ctenos<\/a>.<\/p>\n<p><strong><u>Materiales para la producci\u00f3n de cultivos<\/u><\/strong><br \/>\n<em>(Secci\u00f3n 205.601 de la Lista Nacional)<\/em><\/p>\n<p><strong>Materiales clorados<\/strong> u2013 En vigor desde el 27 de junio de 2012: Para uso previo a la cosecha, los niveles de cloro residual en el agua en contacto directo con el cultivo, o como agua de limpieza de sistemas de riego aplicada al suelo no deben exceder el l\u00edmite m\u00e1ximo de desinfectante residual bajo la Ley de Agua Potable Segura (4ppm). Los productos clorados pueden utilizarse en la producci\u00f3n de brotes comestibles de acuerdo con las instrucciones de la etiqueta de la EPA.<\/p>\n<p><strong>Sulfonato de lignina<\/strong> - En vigor desde el 27 de junio de 2012: Lista duplicada eliminada. Sigue autorizado como enmienda del suelo (quelante, supresor del polvo) y como agente flotante poscosecha.<\/p>\n<p><strong>Estreptomicina y tetraciclina<\/strong> - En vigor el 27 de junio y el 3 de agosto de 2012, respectivamente: La autorizaci\u00f3n para controlar las infecciones en los huertos ecol\u00f3gicos de manzanas y peras se ha ampliado hasta el 21 de octubre de 2014.<\/p>\n<p><strong>Di\u00f3xido de azufre<\/strong> - A partir del 21 de octubre de 2012: El di\u00f3xido de azufre (bombas de humo) ya no ser\u00e1 permitido para el control de roedores en la producci\u00f3n de cultivos org\u00e1nicos. El \u00fanico rodenticida sint\u00e9tico permitido despu\u00e9s del 21 de octubre de 2012 es la vitamina D3 (colecalciferol).<\/p>\n<p><strong><u>Materiales para la producci\u00f3n ganadera<\/u><\/strong><br \/>\n<em>(Secci\u00f3n 205.603 de la Lista Nacional)<\/em><\/p>\n<p><strong>\u00c1cido f\u00f3rmico<\/strong> - En vigor desde el 3 de agosto de 2012: Las explotaciones ap\u00edcolas podr\u00e1n utilizar \u00e1cido f\u00f3rmico como plaguicida \u00fanicamente dentro de las colmenas de abejas mel\u00edferas.<\/p>\n<p><strong><u>Procesador\/manipulador de materiales<\/u><\/strong><br \/>\n<em>(Lista Nacional, secciones 205.605, 205.606)<\/em><\/p>\n<p><strong>Lecitina<\/strong> - En vigor desde el 15 de marzo de 2012: Debe utilizar lecitina ecol\u00f3gica en sus productos ecol\u00f3gicos. Se puede utilizar lecitina no ecol\u00f3gica si la lecitina ecol\u00f3gica no est\u00e1 disponible en el mercado.<\/p>\n<p><strong>Colores<\/strong> - En vigor desde el 27 de junio de 2012: Debe utilizar colorantes ecol\u00f3gicos en sus productos ecol\u00f3gicos. Los colorantes no ecol\u00f3gicos producidos sin disolventes sint\u00e9ticos ni sistemas portadores, y sin conservantes artificiales, pueden utilizarse si los colorantes ecol\u00f3gicos no est\u00e1n disponibles en el mercado.<\/p>\n<p><strong>Pectina<\/strong> - En vigor desde el 27 de junio de 2012: Debe utilizar pectina ecol\u00f3gica en sus productos ecol\u00f3gicos. Se puede utilizar pectina no org\u00e1nica no amidada si la pectina org\u00e1nica no est\u00e1 disponible comercialmente.<\/p>\n<p><strong>Levadura<\/strong> - En vigor desde el 21 de octubre de 2012: Debe utilizar levadura ecol\u00f3gica en sus productos ecol\u00f3gicos. Se puede utilizar levadura no ecol\u00f3gica si la levadura ecol\u00f3gica no est\u00e1 disponible comercialmente. (Este listado NO requiere el uso de levadura ecol\u00f3gica para la alimentaci\u00f3n del ganado).<\/p>\n<p><strong>Attapulgita<\/strong> - En vigor desde el 3 de agosto de 2012: Puede utilizar atapulgita no sint\u00e9tica como coadyuvante tecnol\u00f3gico para la purificaci\u00f3n de aceites vegetales y animales.<\/p>\n<p><strong>L\u00fapulo<\/strong> - A partir del 1 de enero de 2013: Debe utilizar l\u00fapulo ecol\u00f3gico en sus productos ecol\u00f3gicos. Despu\u00e9s del 1 de enero de 2013, no podr\u00e1 utilizar l\u00fapulo no ecol\u00f3gico en ning\u00fan producto ecol\u00f3gico, como la cerveza.<\/p>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>A principios de este a\u00f1o, el Programa Nacional Org\u00e1nico public\u00f3 una norma final que renueva ...<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"0","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"33509,33616,32729,32960,33288,33965,32805,33212,32734,33494","_relevanssi_noindex_reason":"","footnotes":""},"categories":[112],"class_list":["post-32817","post","type-post","status-publish","format-standard","hentry","category-certification-news","language-english","certifications-usda-nop","certification_topics-materials-and-inputs","certification_topics-program-standards"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Updates to National List of Allowed and Prohibited Substances - CCOF.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ccof.org\/es\/news\/updates-to-national-list-of-allowed-and-prohibited-substances\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Updates to National List of Allowed and Prohibited Substances - CCOF.org\" \/>\n<meta property=\"og:description\" content=\"Earlier this year, the National Organic Program published a final rule renewing over &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ccof.org\/es\/news\/updates-to-national-list-of-allowed-and-prohibited-substances\/\" \/>\n<meta property=\"og:site_name\" content=\"CCOF.org\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CCOForganic\" \/>\n<meta property=\"article:published_time\" content=\"2012-12-11T22:08:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-12T19:30:36+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/updates-to-national-list-of-allowed-and-prohibited-substances\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/updates-to-national-list-of-allowed-and-prohibited-substances\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/person\\\/5ccd134e7ab95678db6afcb521a44e07\"},\"headline\":\"Updates to National List of Allowed and Prohibited Substances\",\"datePublished\":\"2012-12-11T22:08:25+00:00\",\"dateModified\":\"2025-08-12T19:30:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/updates-to-national-list-of-allowed-and-prohibited-substances\\\/\"},\"wordCount\":409,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\"},\"articleSection\":[\"Certification News\"],\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/updates-to-national-list-of-allowed-and-prohibited-substances\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/updates-to-national-list-of-allowed-and-prohibited-substances\\\/\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/updates-to-national-list-of-allowed-and-prohibited-substances\\\/\",\"name\":\"Updates to National List of Allowed and Prohibited Substances - CCOF.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#website\"},\"datePublished\":\"2012-12-11T22:08:25+00:00\",\"dateModified\":\"2025-08-12T19:30:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/updates-to-national-list-of-allowed-and-prohibited-substances\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/updates-to-national-list-of-allowed-and-prohibited-substances\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/updates-to-national-list-of-allowed-and-prohibited-substances\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ccof.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Updates to National List of Allowed and Prohibited Substances\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#website\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/\",\"name\":\"CCOF.org\",\"description\":\"Help make organic the norm!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ccof.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\",\"name\":\"CCOF.org\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/ccof-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.ccof.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/ccof-logo.svg\",\"width\":85,\"height\":111,\"caption\":\"CCOF.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CCOForganic\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CCOForganic\",\"https:\\\/\\\/www.instagram.com\\\/ccoforganic\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/person\\\/5ccd134e7ab95678db6afcb521a44e07\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/www.ccof.org\\\/wp\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Actualizaciones de la lista nacional de sustancias permitidas y prohibidas - CCOF.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ccof.org\/es\/news\/updates-to-national-list-of-allowed-and-prohibited-substances\/","og_locale":"es_MX","og_type":"article","og_title":"Updates to National List of Allowed and Prohibited Substances - CCOF.org","og_description":"Earlier this year, the National Organic Program published a final rule renewing over &hellip;","og_url":"https:\/\/www.ccof.org\/es\/news\/updates-to-national-list-of-allowed-and-prohibited-substances\/","og_site_name":"CCOF.org","article_publisher":"https:\/\/www.facebook.com\/CCOForganic","article_published_time":"2012-12-11T22:08:25+00:00","article_modified_time":"2025-08-12T19:30:36+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ccof.org\/es\/news\/updates-to-national-list-of-allowed-and-prohibited-substances\/#article","isPartOf":{"@id":"https:\/\/www.ccof.org\/es\/news\/updates-to-national-list-of-allowed-and-prohibited-substances\/"},"author":{"name":"admin","@id":"https:\/\/www.ccof.org\/#\/schema\/person\/5ccd134e7ab95678db6afcb521a44e07"},"headline":"Updates to National List of Allowed and Prohibited Substances","datePublished":"2012-12-11T22:08:25+00:00","dateModified":"2025-08-12T19:30:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ccof.org\/es\/news\/updates-to-national-list-of-allowed-and-prohibited-substances\/"},"wordCount":409,"commentCount":0,"publisher":{"@id":"https:\/\/www.ccof.org\/#organization"},"articleSection":["Certification News"],"inLanguage":"es-MX","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ccof.org\/es\/news\/updates-to-national-list-of-allowed-and-prohibited-substances\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ccof.org\/es\/news\/updates-to-national-list-of-allowed-and-prohibited-substances\/","url":"https:\/\/www.ccof.org\/es\/news\/updates-to-national-list-of-allowed-and-prohibited-substances\/","name":"Actualizaciones de la lista nacional de sustancias permitidas y prohibidas - CCOF.org","isPartOf":{"@id":"https:\/\/www.ccof.org\/#website"},"datePublished":"2012-12-11T22:08:25+00:00","dateModified":"2025-08-12T19:30:36+00:00","breadcrumb":{"@id":"https:\/\/www.ccof.org\/es\/news\/updates-to-national-list-of-allowed-and-prohibited-substances\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ccof.org\/es\/news\/updates-to-national-list-of-allowed-and-prohibited-substances\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ccof.org\/es\/news\/updates-to-national-list-of-allowed-and-prohibited-substances\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ccof.org\/"},{"@type":"ListItem","position":2,"name":"Updates to National List of Allowed and Prohibited Substances"}]},{"@type":"WebSite","@id":"https:\/\/www.ccof.org\/#website","url":"https:\/\/www.ccof.org\/","name":"CCOF.org","description":"\u00a1Ayude a que lo org\u00e1nico sea la norma!","publisher":{"@id":"https:\/\/www.ccof.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ccof.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.ccof.org\/#organization","name":"CCOF.org","url":"https:\/\/www.ccof.org\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.ccof.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.ccof.org\/wp-content\/uploads\/2024\/02\/ccof-logo.svg","contentUrl":"https:\/\/www.ccof.org\/wp-content\/uploads\/2024\/02\/ccof-logo.svg","width":85,"height":111,"caption":"CCOF.org"},"image":{"@id":"https:\/\/www.ccof.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CCOForganic","https:\/\/www.youtube.com\/c\/CCOForganic","https:\/\/www.instagram.com\/ccoforganic\/"]},{"@type":"Person","@id":"https:\/\/www.ccof.org\/#\/schema\/person\/5ccd134e7ab95678db6afcb521a44e07","name":"admin","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/www.ccof.org\/wp"]}]}},"_links":{"self":[{"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/posts\/32817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/comments?post=32817"}],"version-history":[{"count":4,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/posts\/32817\/revisions"}],"predecessor-version":[{"id":62916,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/posts\/32817\/revisions\/62916"}],"wp:attachment":[{"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/media?parent=32817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/categories?post=32817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}