{"id":33059,"date":"2014-10-27T17:31:56","date_gmt":"2014-10-27T17:31:56","guid":{"rendered":"https:\/\/www.ccof.org\/upcoming-fsma-listening-session\/"},"modified":"2024-04-23T21:06:08","modified_gmt":"2024-04-23T21:06:08","slug":"upcoming-fsma-listening-session","status":"publish","type":"post","link":"https:\/\/www.ccof.org\/es\/news\/upcoming-fsma-listening-session\/","title":{"rendered":"Pr\u00f3xima sesi\u00f3n de escucha sobre la FSMA"},"content":{"rendered":"<p>\u00bfEst\u00e1 al d\u00eda de las \u00faltimas normas propuestas de la Ley de Modernizaci\u00f3n de la Seguridad Alimentaria (FSMA)?<\/p>\n<p><strong>El jueves 6 de noviembre, en Sacramento, California<\/strong>el Departamento de Alimentos y Agricultura de California organizar\u00e1 una sesi\u00f3n de escucha gratuita sobre las normas propuestas actualizadas de la FSMA para la seguridad de los productos, los controles preventivos de los alimentos para consumo humano y los controles preventivos de los alimentos para consumo animal.<\/p>\n<p>El CCOF copatrocina la sesi\u00f3n de escucha y anima a todos los miembros a aprovechar esta oportunidad para escuchar un resumen de las normas propuestas actualizadas, hacer preguntas y obtener m\u00e1s informaci\u00f3n sobre las normas de seguridad alimentaria.<\/p>\n<p>La sesi\u00f3n de escucha se celebrar\u00e1 en el Hyatt Regency, 1209 L St. de Sacramento, de 8.30 a 15.30 horas. El aforo de la sesi\u00f3n ser\u00e1 limitado, por lo que le rogamos que se inscriba (sin coste alguno) para reservar una plaza.<\/p>\n<p>Visite el\u00a0<a data-entity-substitution=\"canonical\"       data-entity-type=\"node\" data-entity-uuid=\"83ae7f74-a78e-441d-a219-bde804c8d964\"       href=\"\/es\/node\/7496\/\">P\u00e1gina del evento<\/a>\u00a0para inscribirse.\u00a0<\/p>\n<figure class=\"content-image\"><\/figure>","protected":false},"excerpt":{"rendered":"<p>\u00bfEst\u00e1 al d\u00eda de las \u00faltimas normas propuestas de la Ley de Modernizaci\u00f3n de la Seguridad Alimentaria (FSMA)? ...<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[110],"class_list":["post-33059","post","type-post","status-publish","format-standard","hentry","category-advocacy-news","language-english","advocacy_campaigns-market-integrity-development"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Upcoming FSMA Listening Session - CCOF.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ccof.org\/es\/news\/upcoming-fsma-listening-session\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Upcoming FSMA Listening Session - CCOF.org\" \/>\n<meta property=\"og:description\" content=\"Are you up-to-date on the latest Food Safety Modernization Act (FSMA) proposed rules? &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ccof.org\/es\/news\/upcoming-fsma-listening-session\/\" \/>\n<meta property=\"og:site_name\" content=\"CCOF.org\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CCOForganic\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-27T17:31:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-23T21:06:08+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/upcoming-fsma-listening-session\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/upcoming-fsma-listening-session\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/person\\\/5ccd134e7ab95678db6afcb521a44e07\"},\"headline\":\"Upcoming FSMA Listening Session\",\"datePublished\":\"2014-10-27T17:31:56+00:00\",\"dateModified\":\"2024-04-23T21:06:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/upcoming-fsma-listening-session\\\/\"},\"wordCount\":132,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\"},\"articleSection\":[\"Advocacy News\"],\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/upcoming-fsma-listening-session\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/upcoming-fsma-listening-session\\\/\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/upcoming-fsma-listening-session\\\/\",\"name\":\"Upcoming FSMA Listening Session - CCOF.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#website\"},\"datePublished\":\"2014-10-27T17:31:56+00:00\",\"dateModified\":\"2024-04-23T21:06:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/upcoming-fsma-listening-session\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/upcoming-fsma-listening-session\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/upcoming-fsma-listening-session\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ccof.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Upcoming FSMA Listening Session\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#website\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/\",\"name\":\"CCOF.org\",\"description\":\"Help make organic the norm!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ccof.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\",\"name\":\"CCOF.org\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/ccof-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.ccof.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/ccof-logo.svg\",\"width\":85,\"height\":111,\"caption\":\"CCOF.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CCOForganic\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CCOForganic\",\"https:\\\/\\\/www.instagram.com\\\/ccoforganic\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/person\\\/5ccd134e7ab95678db6afcb521a44e07\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/www.ccof.org\\\/wp\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pr\u00f3xima sesi\u00f3n de escucha sobre la FSMA - CCOF.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ccof.org\/es\/news\/upcoming-fsma-listening-session\/","og_locale":"es_MX","og_type":"article","og_title":"Upcoming FSMA Listening Session - CCOF.org","og_description":"Are you up-to-date on the latest Food Safety Modernization Act (FSMA) proposed rules? &hellip;","og_url":"https:\/\/www.ccof.org\/es\/news\/upcoming-fsma-listening-session\/","og_site_name":"CCOF.org","article_publisher":"https:\/\/www.facebook.com\/CCOForganic","article_published_time":"2014-10-27T17:31:56+00:00","article_modified_time":"2024-04-23T21:06:08+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ccof.org\/es\/news\/upcoming-fsma-listening-session\/#article","isPartOf":{"@id":"https:\/\/www.ccof.org\/es\/news\/upcoming-fsma-listening-session\/"},"author":{"name":"admin","@id":"https:\/\/www.ccof.org\/#\/schema\/person\/5ccd134e7ab95678db6afcb521a44e07"},"headline":"Upcoming FSMA Listening Session","datePublished":"2014-10-27T17:31:56+00:00","dateModified":"2024-04-23T21:06:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ccof.org\/es\/news\/upcoming-fsma-listening-session\/"},"wordCount":132,"commentCount":0,"publisher":{"@id":"https:\/\/www.ccof.org\/#organization"},"articleSection":["Advocacy News"],"inLanguage":"es-MX","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ccof.org\/es\/news\/upcoming-fsma-listening-session\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ccof.org\/es\/news\/upcoming-fsma-listening-session\/","url":"https:\/\/www.ccof.org\/es\/news\/upcoming-fsma-listening-session\/","name":"Pr\u00f3xima sesi\u00f3n de escucha sobre la FSMA - CCOF.org","isPartOf":{"@id":"https:\/\/www.ccof.org\/#website"},"datePublished":"2014-10-27T17:31:56+00:00","dateModified":"2024-04-23T21:06:08+00:00","breadcrumb":{"@id":"https:\/\/www.ccof.org\/es\/news\/upcoming-fsma-listening-session\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ccof.org\/es\/news\/upcoming-fsma-listening-session\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ccof.org\/es\/news\/upcoming-fsma-listening-session\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ccof.org\/"},{"@type":"ListItem","position":2,"name":"Upcoming FSMA Listening Session"}]},{"@type":"WebSite","@id":"https:\/\/www.ccof.org\/#website","url":"https:\/\/www.ccof.org\/","name":"CCOF.org","description":"\u00a1Ayude a que lo org\u00e1nico sea la norma!","publisher":{"@id":"https:\/\/www.ccof.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ccof.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.ccof.org\/#organization","name":"CCOF.org","url":"https:\/\/www.ccof.org\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.ccof.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.ccof.org\/wp-content\/uploads\/2024\/02\/ccof-logo.svg","contentUrl":"https:\/\/www.ccof.org\/wp-content\/uploads\/2024\/02\/ccof-logo.svg","width":85,"height":111,"caption":"CCOF.org"},"image":{"@id":"https:\/\/www.ccof.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CCOForganic","https:\/\/www.youtube.com\/c\/CCOForganic","https:\/\/www.instagram.com\/ccoforganic\/"]},{"@type":"Person","@id":"https:\/\/www.ccof.org\/#\/schema\/person\/5ccd134e7ab95678db6afcb521a44e07","name":"admin","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/www.ccof.org\/wp"]}]}},"_links":{"self":[{"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/posts\/33059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/comments?post=33059"}],"version-history":[{"count":2,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/posts\/33059\/revisions"}],"predecessor-version":[{"id":35729,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/posts\/33059\/revisions\/35729"}],"wp:attachment":[{"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/media?parent=33059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/categories?post=33059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}