{"id":33547,"date":"2021-02-08T19:06:50","date_gmt":"2021-02-08T19:06:50","guid":{"rendered":"https:\/\/www.ccof.org\/uc-davis-seeks-information-on-dried-fruit-production\/"},"modified":"2024-04-23T21:07:41","modified_gmt":"2024-04-23T21:07:41","slug":"uc-davis-seeks-information-on-dried-fruit-production","status":"publish","type":"post","link":"https:\/\/www.ccof.org\/es\/news\/uc-davis-seeks-information-on-dried-fruit-production\/","title":{"rendered":"UC Davis busca informaci\u00f3n sobre la producci\u00f3n de frutos secos"},"content":{"rendered":"<p>La Universidad de California en Davis quiere conocer la opini\u00f3n de los procesadores de frutos secos de California.<\/p>\n<p>California es un importante productor de frutos secos, y en UC Davis queremos apoyar la producci\u00f3n de productos secos de alta calidad. Un equipo de investigadores del Departamento de Ciencia y Tecnolog\u00eda de los Alimentos est\u00e1 interesado en desarrollar orientaciones sobre las mejores pr\u00e1cticas para garantizar la seguridad y la calidad de los cultivos especiales deshidratados de California.<\/p>\n<p>Para apoyar a nuestros productores de fruta deshidratada de California, necesitamos informaci\u00f3n sobre las pr\u00e1cticas industriales m\u00e1s comunes que se emplean actualmente para deshidratar. \u00bfSecan al sol o utilizan un deshidratador mec\u00e1nico? Queremos saber. \u00bfAplica un tratamiento qu\u00edmico para reducir el oscurecimiento y aumentar la vida \u00fatil? Queremos saberlo. La informaci\u00f3n recopilada servir\u00e1 para establecer prioridades de investigaci\u00f3n y orientaciones que los productores puedan utilizar para mejorar los procesos y cumplir los requisitos normativos.<\/p>\n<p>Por favor, considere la posibilidad de proporcionar informaci\u00f3n sobre su proceso para informar a nuestro equipo. Nuestro objetivo es apoyar a la industria y mejorar los canales de mercado potenciales para los procesadores de frutos secos.<\/p>\n<p>Los envases de la <a       href=\"https:\/\/ucdavis.co1.qualtrics.com\/jfe\/form\/SV_82kXUJdSqeoZtd3\">encuesta<\/a>       le llevar\u00e1 aproximadamente entre 5 y 10 minutos de su tiempo.<\/p>\n<p>Si tiene alguna pregunta sobre la encuesta o sobre los esfuerzos en curso para apoyar a los procesadores de frutos secos, p\u00f3ngase en contacto con la Dra. Erin DiCaprio en el (530) 752-6594 o en el <a       href=\"mailto:eldicaprio@ucdavis.edu\">eldicaprio@ucdavis.edu<\/a>.<\/p>\n<p><em>*       * *<\/em><\/p>\n<p><strong><em>Este art\u00edculo ha sido escrito por Erin DiCaprio. <\/em><\/strong><\/p>\n<p><strong><em>Sobre el autor:<\/em><\/strong><em> Erin DiCaprio es especialista adjunta en seguridad alimentaria comunitaria de la Extensi\u00f3n Cooperativa de la Universidad de California. El \u00e1rea de especializaci\u00f3n de la Dra. DiCaprio es la seguridad alimentaria microbiana, con \u00e9nfasis en los virus transmitidos por los alimentos. Los virus son una de las principales causas de enfermedades transmitidas por los alimentos, y los alimentos de alto riesgo de contaminaci\u00f3n v\u00edrica son los productos frescos, el marisco y los alimentos listos para el consumo. Sus investigaciones se centran en determinar los mecanismos por los que los productos frescos se contaminan con virus transmitidos por los alimentos durante su producci\u00f3n y procesado y qu\u00e9 factores biol\u00f3gicos y ambientales influyen en la persistencia de los virus en estos alimentos.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>La Universidad de California en Davis quiere conocer la opini\u00f3n de los procesadores de frutos secos de California. California ...<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[111],"class_list":["post-33547","post","type-post","status-publish","format-standard","hentry","category-foundation-news","language-english","foundation_topics-education"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UC Davis Seeks Information on Dried Fruit Production - CCOF.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.ccof.org\/es\/news\/uc-davis-seeks-information-on-dried-fruit-production\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UC Davis Seeks Information on Dried Fruit Production - CCOF.org\" \/>\n<meta property=\"og:description\" content=\"University of California, Davis wants to hear from California dried fruit processors. California &hellip;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.ccof.org\/es\/news\/uc-davis-seeks-information-on-dried-fruit-production\/\" \/>\n<meta property=\"og:site_name\" content=\"CCOF.org\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CCOForganic\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-08T19:06:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-23T21:07:41+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/uc-davis-seeks-information-on-dried-fruit-production\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/uc-davis-seeks-information-on-dried-fruit-production\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/person\\\/5ccd134e7ab95678db6afcb521a44e07\"},\"headline\":\"UC Davis Seeks Information on Dried Fruit Production\",\"datePublished\":\"2021-02-08T19:06:50+00:00\",\"dateModified\":\"2024-04-23T21:07:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/uc-davis-seeks-information-on-dried-fruit-production\\\/\"},\"wordCount\":306,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\"},\"articleSection\":[\"Foundation News\"],\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/uc-davis-seeks-information-on-dried-fruit-production\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/uc-davis-seeks-information-on-dried-fruit-production\\\/\",\"url\":\"http:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/uc-davis-seeks-information-on-dried-fruit-production\\\/\",\"name\":\"UC Davis Seeks Information on Dried Fruit Production - CCOF.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#website\"},\"datePublished\":\"2021-02-08T19:06:50+00:00\",\"dateModified\":\"2024-04-23T21:07:41+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/uc-davis-seeks-information-on-dried-fruit-production\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/uc-davis-seeks-information-on-dried-fruit-production\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/uc-davis-seeks-information-on-dried-fruit-production\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ccof.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UC Davis Seeks Information on Dried Fruit Production\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#website\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/\",\"name\":\"CCOF.org\",\"description\":\"Help make organic the norm!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ccof.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\",\"name\":\"CCOF.org\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/ccof-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.ccof.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/ccof-logo.svg\",\"width\":85,\"height\":111,\"caption\":\"CCOF.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CCOForganic\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CCOForganic\",\"https:\\\/\\\/www.instagram.com\\\/ccoforganic\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/person\\\/5ccd134e7ab95678db6afcb521a44e07\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/www.ccof.org\\\/wp\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UC Davis busca informaci\u00f3n sobre la producci\u00f3n de frutos secos - CCOF.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.ccof.org\/es\/news\/uc-davis-seeks-information-on-dried-fruit-production\/","og_locale":"es_MX","og_type":"article","og_title":"UC Davis Seeks Information on Dried Fruit Production - CCOF.org","og_description":"University of California, Davis wants to hear from California dried fruit processors. California &hellip;","og_url":"http:\/\/www.ccof.org\/es\/news\/uc-davis-seeks-information-on-dried-fruit-production\/","og_site_name":"CCOF.org","article_publisher":"https:\/\/www.facebook.com\/CCOForganic","article_published_time":"2021-02-08T19:06:50+00:00","article_modified_time":"2024-04-23T21:07:41+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.ccof.org\/es\/news\/uc-davis-seeks-information-on-dried-fruit-production\/#article","isPartOf":{"@id":"http:\/\/www.ccof.org\/es\/news\/uc-davis-seeks-information-on-dried-fruit-production\/"},"author":{"name":"admin","@id":"https:\/\/www.ccof.org\/#\/schema\/person\/5ccd134e7ab95678db6afcb521a44e07"},"headline":"UC Davis Seeks Information on Dried Fruit Production","datePublished":"2021-02-08T19:06:50+00:00","dateModified":"2024-04-23T21:07:41+00:00","mainEntityOfPage":{"@id":"http:\/\/www.ccof.org\/es\/news\/uc-davis-seeks-information-on-dried-fruit-production\/"},"wordCount":306,"commentCount":0,"publisher":{"@id":"https:\/\/www.ccof.org\/#organization"},"articleSection":["Foundation News"],"inLanguage":"es-MX","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/www.ccof.org\/es\/news\/uc-davis-seeks-information-on-dried-fruit-production\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/www.ccof.org\/es\/news\/uc-davis-seeks-information-on-dried-fruit-production\/","url":"http:\/\/www.ccof.org\/es\/news\/uc-davis-seeks-information-on-dried-fruit-production\/","name":"UC Davis busca informaci\u00f3n sobre la producci\u00f3n de frutos secos - CCOF.org","isPartOf":{"@id":"https:\/\/www.ccof.org\/#website"},"datePublished":"2021-02-08T19:06:50+00:00","dateModified":"2024-04-23T21:07:41+00:00","breadcrumb":{"@id":"http:\/\/www.ccof.org\/es\/news\/uc-davis-seeks-information-on-dried-fruit-production\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.ccof.org\/es\/news\/uc-davis-seeks-information-on-dried-fruit-production\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.ccof.org\/es\/news\/uc-davis-seeks-information-on-dried-fruit-production\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ccof.org\/"},{"@type":"ListItem","position":2,"name":"UC Davis Seeks Information on Dried Fruit Production"}]},{"@type":"WebSite","@id":"https:\/\/www.ccof.org\/#website","url":"https:\/\/www.ccof.org\/","name":"CCOF.org","description":"\u00a1Ayude a que lo org\u00e1nico sea la norma!","publisher":{"@id":"https:\/\/www.ccof.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ccof.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.ccof.org\/#organization","name":"CCOF.org","url":"https:\/\/www.ccof.org\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.ccof.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.ccof.org\/wp-content\/uploads\/2024\/02\/ccof-logo.svg","contentUrl":"https:\/\/www.ccof.org\/wp-content\/uploads\/2024\/02\/ccof-logo.svg","width":85,"height":111,"caption":"CCOF.org"},"image":{"@id":"https:\/\/www.ccof.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CCOForganic","https:\/\/www.youtube.com\/c\/CCOForganic","https:\/\/www.instagram.com\/ccoforganic\/"]},{"@type":"Person","@id":"https:\/\/www.ccof.org\/#\/schema\/person\/5ccd134e7ab95678db6afcb521a44e07","name":"admin","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/www.ccof.org\/wp"]}]}},"_links":{"self":[{"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/posts\/33547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/comments?post=33547"}],"version-history":[{"count":2,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/posts\/33547\/revisions"}],"predecessor-version":[{"id":36218,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/posts\/33547\/revisions\/36218"}],"wp:attachment":[{"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/media?parent=33547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/categories?post=33547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}