{"id":34029,"date":"2024-01-31T19:04:31","date_gmt":"2024-01-31T19:04:31","guid":{"rendered":"https:\/\/www.ccof.org\/millions-available-for-special-conservation-priorities-in-california\/"},"modified":"2024-04-23T21:09:58","modified_gmt":"2024-04-23T21:09:58","slug":"millions-available-for-special-conservation-priorities-in-california","status":"publish","type":"post","link":"https:\/\/www.ccof.org\/es\/news\/millions-available-for-special-conservation-priorities-in-california\/","title":{"rendered":"Millones disponibles para prioridades especiales de conservaci\u00f3n en California"},"content":{"rendered":"<p>El Servicio de Conservaci\u00f3n de Recursos Naturales (NRCS) del USDA en California est\u00e1 aceptando solicitudes para tres prioridades populares de conservaci\u00f3n hasta el 16 de febrero de 2024.       Esta financiaci\u00f3n se suma a los millones disponibles para los productores agr\u00edcolas de California a trav\u00e9s del programa regular de <a       href=\"https:\/\/www.nrcs.usda.gov\/programs-initiatives\/eqip-environmental-quality-incentives\/california\/environmental-quality\">Programa de Incentivos a la Calidad Medioambiental<\/a> (EQIP) y la nueva Ley de Reducci\u00f3n de la Inflaci\u00f3n.<\/p>\n<p>\"NRCS California se ha comprometido a ayudar a los productores agr\u00edcolas para hacer frente a las necesidades cr\u00edticas de recursos en todo el estado, y estas tres iniciativas populares ir a\u00fan m\u00e1s lejos con mejoras estrat\u00e9gicas en las granjas y ranchos\", dijo NRCS Conservador del Estado de California Carlos Su\u00e1rez. \"Adem\u00e1s, estas tres iniciativas traen importantes socios org\u00e1nicos y de calidad del agua a la mesa para ayudarnos a satisfacer mejor las necesidades de los productores.\"<\/p>\n<p>Los propietarios interesados deben ponerse en contacto con sus oficinas locales del NRCS lo antes posible o visitar <a       href=\"https:\/\/www.nrcs.usda.gov\/contact\/find-a-service-center\">https:\/\/www.nrcs.usda.gov\/contact\/find-a-service-center<\/a>.<\/p>\n<p>A trav\u00e9s del EQIP, hay millones de d\u00f3lares disponibles para pr\u00e1cticas e iniciativas de conservaci\u00f3n, entre las que se incluyen las siguientes:<\/p>\n<ul><\/p>\n<li>NRCS y Bureau of Reclamation <a       href=\"https:\/\/www.nrcs.usda.gov\/programs-initiatives\/watersmart\/california\/watersmart-california\">WaterSMART<\/a>       para ayudar a mejorar las infraestructuras, el suministro y la aplicaci\u00f3n del agua en las explotaciones agr\u00edcolas.       Tres nuevos proyectos seleccionados para el a\u00f1o fiscal 2024 incluyen zonas de los condados de Fresno y Tulare.<\/li>\n<figure class=\"content-image\"><\/figure>\n<li><a       href=\"https:\/\/www.nrcs.usda.gov\/programs-initiatives\/eqip-national-water-quality-initiative\/california\/water-quality-initiative\">Iniciativa Nacional para la Calidad del Agua<\/a> para acciones de conservaci\u00f3n espec\u00edficas destinadas a mejorar la calidad del agua. Dos nuevos proyectos para el ejercicio 2024 incluyen la cuenca hidrogr\u00e1fica de Clearlake (condado de Lake) y la cuenca hidrogr\u00e1fica de Pescadero (condado de San Mateo).<\/li>\n<figure class=\"content-image\"><\/figure>\n<li>El nuevo <a       href=\"https:\/\/www.nrcs.usda.gov\/sites\/default\/files\/2023-04\/2023-NRCS-Organic       Transition Initiative Fact Sheet.pdf\">Iniciativa de Transici\u00f3n Org\u00e1nica<\/a> que ayuda a los agricultores interesados en la transici\u00f3n a m\u00e9todos de agricultura org\u00e1nica.\u00a0<\/li>\n<p><\/ul>\n<p>El EQIP proporciona ayuda financiera a los productores agr\u00edcolas para abordar los problemas relacionados con los recursos naturales y ofrecer beneficios medioambientales. Entre ellos se incluyen la mejora de la calidad del agua y del aire, la mejora de la eficiencia del riego, la reducci\u00f3n de la erosi\u00f3n del suelo y la sedimentaci\u00f3n, la restauraci\u00f3n forestal y la creaci\u00f3n o mejora del h\u00e1bitat de la fauna silvestre. La Organic Farming Research Foundation ha creado gu\u00edas para solicitar el EQIP en       <a       href=\"https:\/\/ofrf.org\/wp-content\/uploads\/2023\/12\/EQIP.pdf\">Ingl\u00e9s<\/a> y       <a       href=\"https:\/\/ofrf.org\/wp-content\/uploads\/2023\/12\/EQIP-Espanol.pdf\">Espa\u00f1ol<\/a>.<\/p>\n<h4><strong>Asistencia t\u00e9cnica gratuita<\/strong><\/h4>\n<p>La NRCS ofrece asistencia t\u00e9cnica en conservaci\u00f3n sin coste alguno para proporcionar a los productores asesoramiento e informaci\u00f3n personalizados, basados en los \u00faltimos avances cient\u00edficos y en la investigaci\u00f3n, para ayudarles a tomar decisiones informadas. Si un productor decide dar el siguiente paso para mejorar sus operaciones, el personal del NRCS puede trabajar con \u00e9l para desarrollar un plan de conservaci\u00f3n personalizado y gratuito, con pr\u00e1cticas de conservaci\u00f3n que puedan ayudarle a alcanzar sus objetivos de producci\u00f3n agr\u00edcola y conservaci\u00f3n. Normalmente, el plan incluir\u00e1 mapas de uso de la tierra, informaci\u00f3n sobre los suelos, inventario de recursos, notas de ingenier\u00eda y otra informaci\u00f3n de apoyo.<\/p>\n<h4><strong>Beneficios para los productores hist\u00f3ricamente subatendidos<\/strong><\/h4>\n<p>Tambi\u00e9n existen disposiciones especiales para <a       href=\"https:\/\/www.nrcs.usda.gov\/wps\/portal\/nrcs\/main\/national\/people\/outreach\/slbfr\/\">productores hist\u00f3ricamente desatendidos<\/a>. En el caso del EQIP, los productores hist\u00f3ricamente desfavorecidos pueden optar a anticipos que les ayuden a compensar los costes relacionados con la compra de materiales o la contrataci\u00f3n de servicios por adelantado. Adem\u00e1s, los productores hist\u00f3ricamente subatendidos pueden recibir porcentajes de pago del EQIP m\u00e1s elevados (hasta el 90% del coste medio). El NRCS reserva fondos del EQIP y del Conservation Stewardship Program (CSP) para los productores hist\u00f3ricamente desatendidos.<\/p>\n<h4><strong>Qui\u00e9nes somos<\/strong><\/h4>\n<p>Desde 1935, la NRCS lidera un esfuerzo de colaboraci\u00f3n para ayudar a los propietarios y gestores privados de tierras de Estados Unidos a conservar el suelo, el agua y otros recursos naturales. Para m\u00e1s informaci\u00f3n, visite <a       href=\"https:\/\/www.nrcs.usda.gov\/conservation-basics\/conservation-by-state\/california\">https:\/\/www.nrcs.usda.gov\/conservation-basics\/conservation-by-state\/california<\/a>.<\/p>\n<p>Adaptado de un <a       href=\"https:\/\/www.nrcs.usda.gov\/news\/millions-available-for-special-conservation-priorities-in-california\">Comunicado de prensa del NRCS<\/a> publicado el 22 de noviembre de 2023.\u00a0<\/p>\n<p>\u201c,\u201d<\/p>\n<p>El Servicio de Conservaci\u00f3n de Recursos Naturales (NRCS) de USDA en California est\u00e1 recibiendo postulaciones para tres prioridades de conservaci\u00f3n hasta el 16 de febrero de 2024. Este financiamiento es adicional a los millones disponibles para los productores agr\u00edcolas de California mediante el <a       href=\"https:\/\/www.nrcs.usda.gov\/programs-initiatives\/eqip-environmental-quality-incentives\/california\/environmental-quality\">Programa de Incentivos de Calidad Medioambiental<\/a> (EQIP) y la nueva Ley para Reducir la Inflaci\u00f3n.<\/p>\n<p>\"El compromiso de NRCS California es brindar asistencia a los productores agr\u00edcolas con el fin de que resuelvan las necesidades cr\u00edticas de recursos en todo el estado y estas tres iniciativas van incluso m\u00e1s all\u00e1 pues a\u00f1aden mejoras estrat\u00e9gicas a las granjas y ranchos\", coment\u00f3 el conservacionista de NRCS del estado de California, Carlos Su\u00e1rez.       \"Adem\u00e1s, con estas tres iniciativas se cuenta con la contribuci\u00f3n de importantes aliados en materia de calidad del agua y agricultura org\u00e1nica, quienes nos ayudar\u00e1n a satisfacer mejor las necesidades de los productores\".<\/p>\n<p>Los propietarios de tierras que se interesen deber\u00e1n comunicarse lo antes posible con sus oficinas locales del NRCS o visitar el sitio       <a       href=\"https:\/\/www.nrcs.usda.gov\/contact\/find-a-service-center\">https:\/\/www.nrcs.usda.gov\/contact\/find-a-service-center<\/a>.<\/p>\n<p>Por medio de EQIP se cuenta con millones para invertir en pr\u00e1cticas e iniciativas de conservaci\u00f3n, entre las que se encuentran:<\/p>\n<ul><\/p>\n<li>Proyectos en alianza del NRCS y el Departamento de Recuperaciones <a       href=\"https:\/\/www.nrcs.usda.gov\/programs-initiatives\/watersmart\/california\/watersmart-california\">WaterSmart<\/a>       que ayudar\u00e1n a mejorar la infraestructura, entrega y aplicaci\u00f3n del agua en granjas.       Para el a\u00f1o fiscal 2024 se seleccionaron tres nuevos proyectos que incluyen \u00e1reas en los condados de Fresno y Tulare.<\/li>\n<figure class=\"content-image\"><\/figure>\n<li><a       href=\"https:\/\/www.nrcs.usda.gov\/programs-initiatives\/eqip-national-water-quality-initiative\/california\/water-quality-initiative\">Iniciativa nacional para la calidad del agua<\/a> para acciones de conservaci\u00f3n enfocadas a mejorar la calidad del agua. Dos de los nuevos proyectos para el a\u00f1o fiscal 2024 incluyen la Cuenca de Clearlake (Condado Lake) y la Cuenca de Pescadero (Condado de San Mateo).<\/li>\n<figure class=\"content-image\"><\/figure>\n<li>La nueva <a       href=\"https:\/\/www.nrcs.usda.gov\/sites\/default\/files\/2023-04\/2023-NRCS-Organic%20Transition%20Initiative%20Fact%20Sheet.pdf\">Iniciativa de transici\u00f3n org\u00e1nica<\/a> que ayuda a los agricultores interesados a cambiar a m\u00e9todos agr\u00edcolas org\u00e1nicos.\u00a0<\/li>\n<p><\/ul>\n<p>EQIP ofrece asistencia financiera a los productores agr\u00edcolas para que resuelvan problemas relacionados con los recursos naturales y beneficien el medio ambiente. Entro lo anterior se incluye: la mejora de la calidad del aire y el agua, una mejor eficiencia de irrigaci\u00f3n, reducir la erosi\u00f3n y sedimentaci\u00f3n del suelo, reforestar los bosques y crear o mejorar el h\u00e1bitat de la vida silvestre. La Fundaci\u00f3n de Investigaci\u00f3n para la Agricultura Org\u00e1nica ha creado pautas para postularse para EQIP en <a       href=\"https:\/\/ofrf.org\/wp-content\/uploads\/2023\/12\/EQIP.pdf\">ingl\u00e9s       <\/a>y <a       href=\"https:\/\/ofrf.org\/wp-content\/uploads\/2023\/12\/EQIP-Espanol.pdf\">english<\/a>.<\/p>\n<h4><strong>Asistencia t\u00e9cnica gratuita<\/strong><\/h4>\n<p>NRCS ofrece asistencia t\u00e9cnica en materia de conservaci\u00f3n sin costo mediante la cual se le brinda a los productores asesor\u00eda e informaci\u00f3n personalizada con base en la investigaci\u00f3n y la ciencia m\u00e1s recientes con el fin de que tomen decisiones informadas. Si un productor decide dar los siguientes pasos para mejorar sus operaciones, el personal de NRCS puede trabajar con ellos para desarrollar un plan de conservaci\u00f3n, de manera gratuita y personalizada, que incluya pr\u00e1cticas de conservaci\u00f3n que les ayuden a lograr sus metas de conservaci\u00f3n y producci\u00f3n agr\u00edcola. Por lo general, el plan incluye mapas de uso de suelo, informaci\u00f3n de suelos, inventario de recursos, notas de ingenier\u00eda y otra informaci\u00f3n de apoyo.<\/p>\n<h4><strong>Beneficios para productores hist\u00f3ricamente desfavorecidos<\/strong><\/h4>\n<p>Tambi\u00e9n se cuenta con disposiciones especiales para <a       href=\"https:\/\/www.nrcs.usda.gov\/wps\/portal\/nrcs\/main\/national\/people\/outreach\/slbfr\/\">productores hist\u00f3ricamente desatendidos<\/a>. Para EQIP, los productores hist\u00f3ricamente desatendidos re\u00fanen los requisitos para pagos anticipados que les permitan compensar los costes relacionados con la compra de materiales o la contrataci\u00f3n de servicios por anticipado. Adem\u00e1s, los productores hist\u00f3ricamente desatendidos pueden recibir tarifas de pago de EQIP m\u00e1s altas (hasta 90% del coste medio). NRCS tiene separados fondos de EQIP y CSP para los productores hist\u00f3ricamente desatendidos.<\/p>\n<h4><strong>Nosotros<\/strong><\/h4>\n<p>Desde 1935 la NRCS ha sido l\u00edder en establecer alianzas que ayuden a los propietarios y administradores de tierras privadas en los Estados Unidos a conservar su suelo, agua y otros recursos naturales. Para m\u00e1s informaci\u00f3n, visite <a       href=\"https:\/\/www.nrcs.usda.gov\/conservation-basics\/conservation-by-state\/california\">https:\/\/www.nrcs.usda.gov\/conservation-basics\/conservation-by-state\/california<\/a>.<\/p>\n<p>Adaptado de un <a       href=\"https:\/\/www.nrcs.usda.gov\/news\/millions-available-for-special-conservation-priorities-in-california\">Comunicado de prensa de NRCS<\/a> publicado el 22 de noviembre de 2023.<\/p>\n<figure class=\"content-image\"><\/figure>","protected":false},"excerpt":{"rendered":"<p>El Servicio de Conservaci\u00f3n de Recursos Naturales (NRCS) del USDA en California est\u00e1 aceptando solicitudes para ...<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[1],"class_list":["post-34029","post","type-post","status-publish","format-standard","hentry","category-uncategorized","language-english"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Millions Available for Special Conservation Priorities in California - CCOF.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ccof.org\/es\/news\/millions-available-for-special-conservation-priorities-in-california\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Millions Available for Special Conservation Priorities in California - CCOF.org\" \/>\n<meta property=\"og:description\" content=\"The USDA Natural Resources Conservation Service (NRCS) in California is accepting applications for &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ccof.org\/es\/news\/millions-available-for-special-conservation-priorities-in-california\/\" \/>\n<meta property=\"og:site_name\" content=\"CCOF.org\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CCOForganic\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-31T19:04:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-23T21:09:58+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/millions-available-for-special-conservation-priorities-in-california\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/millions-available-for-special-conservation-priorities-in-california\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/person\\\/5ccd134e7ab95678db6afcb521a44e07\"},\"headline\":\"Millions Available for Special Conservation Priorities in California\",\"datePublished\":\"2024-01-31T19:04:31+00:00\",\"dateModified\":\"2024-04-23T21:09:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/millions-available-for-special-conservation-priorities-in-california\\\/\"},\"wordCount\":1187,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/millions-available-for-special-conservation-priorities-in-california\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/millions-available-for-special-conservation-priorities-in-california\\\/\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/millions-available-for-special-conservation-priorities-in-california\\\/\",\"name\":\"Millions Available for Special Conservation Priorities in California - CCOF.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#website\"},\"datePublished\":\"2024-01-31T19:04:31+00:00\",\"dateModified\":\"2024-04-23T21:09:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/millions-available-for-special-conservation-priorities-in-california\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/millions-available-for-special-conservation-priorities-in-california\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/es\\\/news\\\/millions-available-for-special-conservation-priorities-in-california\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ccof.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Millions Available for Special Conservation Priorities in California\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#website\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/\",\"name\":\"CCOF.org\",\"description\":\"Help make organic the norm!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ccof.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\",\"name\":\"CCOF.org\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/ccof-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.ccof.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/ccof-logo.svg\",\"width\":85,\"height\":111,\"caption\":\"CCOF.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CCOForganic\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CCOForganic\",\"https:\\\/\\\/www.instagram.com\\\/ccoforganic\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/person\\\/5ccd134e7ab95678db6afcb521a44e07\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/www.ccof.org\\\/wp\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Millones disponibles para prioridades especiales de conservaci\u00f3n en California - CCOF.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ccof.org\/es\/news\/millions-available-for-special-conservation-priorities-in-california\/","og_locale":"es_MX","og_type":"article","og_title":"Millions Available for Special Conservation Priorities in California - CCOF.org","og_description":"The USDA Natural Resources Conservation Service (NRCS) in California is accepting applications for &hellip;","og_url":"https:\/\/www.ccof.org\/es\/news\/millions-available-for-special-conservation-priorities-in-california\/","og_site_name":"CCOF.org","article_publisher":"https:\/\/www.facebook.com\/CCOForganic","article_published_time":"2024-01-31T19:04:31+00:00","article_modified_time":"2024-04-23T21:09:58+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ccof.org\/es\/news\/millions-available-for-special-conservation-priorities-in-california\/#article","isPartOf":{"@id":"https:\/\/www.ccof.org\/es\/news\/millions-available-for-special-conservation-priorities-in-california\/"},"author":{"name":"admin","@id":"https:\/\/www.ccof.org\/#\/schema\/person\/5ccd134e7ab95678db6afcb521a44e07"},"headline":"Millions Available for Special Conservation Priorities in California","datePublished":"2024-01-31T19:04:31+00:00","dateModified":"2024-04-23T21:09:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ccof.org\/es\/news\/millions-available-for-special-conservation-priorities-in-california\/"},"wordCount":1187,"commentCount":0,"publisher":{"@id":"https:\/\/www.ccof.org\/#organization"},"inLanguage":"es-MX","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ccof.org\/es\/news\/millions-available-for-special-conservation-priorities-in-california\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ccof.org\/es\/news\/millions-available-for-special-conservation-priorities-in-california\/","url":"https:\/\/www.ccof.org\/es\/news\/millions-available-for-special-conservation-priorities-in-california\/","name":"Millones disponibles para prioridades especiales de conservaci\u00f3n en California - CCOF.org","isPartOf":{"@id":"https:\/\/www.ccof.org\/#website"},"datePublished":"2024-01-31T19:04:31+00:00","dateModified":"2024-04-23T21:09:58+00:00","breadcrumb":{"@id":"https:\/\/www.ccof.org\/es\/news\/millions-available-for-special-conservation-priorities-in-california\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ccof.org\/es\/news\/millions-available-for-special-conservation-priorities-in-california\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ccof.org\/es\/news\/millions-available-for-special-conservation-priorities-in-california\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ccof.org\/"},{"@type":"ListItem","position":2,"name":"Millions Available for Special Conservation Priorities in California"}]},{"@type":"WebSite","@id":"https:\/\/www.ccof.org\/#website","url":"https:\/\/www.ccof.org\/","name":"CCOF.org","description":"\u00a1Ayude a que lo org\u00e1nico sea la norma!","publisher":{"@id":"https:\/\/www.ccof.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ccof.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.ccof.org\/#organization","name":"CCOF.org","url":"https:\/\/www.ccof.org\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.ccof.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.ccof.org\/wp-content\/uploads\/2024\/02\/ccof-logo.svg","contentUrl":"https:\/\/www.ccof.org\/wp-content\/uploads\/2024\/02\/ccof-logo.svg","width":85,"height":111,"caption":"CCOF.org"},"image":{"@id":"https:\/\/www.ccof.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CCOForganic","https:\/\/www.youtube.com\/c\/CCOForganic","https:\/\/www.instagram.com\/ccoforganic\/"]},{"@type":"Person","@id":"https:\/\/www.ccof.org\/#\/schema\/person\/5ccd134e7ab95678db6afcb521a44e07","name":"admin","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/www.ccof.org\/wp"]}]}},"_links":{"self":[{"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/posts\/34029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/comments?post=34029"}],"version-history":[{"count":3,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/posts\/34029\/revisions"}],"predecessor-version":[{"id":42086,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/posts\/34029\/revisions\/42086"}],"wp:attachment":[{"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/media?parent=34029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/categories?post=34029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}