{"id":34051,"date":"2024-03-08T17:16:55","date_gmt":"2024-03-08T17:16:55","guid":{"rendered":"https:\/\/www.ccof.org\/join-usda-undersecretary-jenny-lester-moffitt-and-ccof-at-expo-west\/"},"modified":"2024-04-23T21:10:02","modified_gmt":"2024-04-23T21:10:02","slug":"join-usda-undersecretary-jenny-lester-moffitt-and-ccof-at-expo-west","status":"publish","type":"post","link":"https:\/\/www.ccof.org\/es\/news\/join-usda-undersecretary-jenny-lester-moffitt-and-ccof-at-expo-west\/","title":{"rendered":"\u00danase a la Subsecretaria del USDA Jenny Lester Moffitt y al CCOF en Expo West"},"content":{"rendered":"<p>\u00bfVa a asistir a la Natural Products Expo West?\u00a0<\/p>\n<p>\u00danase al CCOF para <a href=\"https:\/\/expowest24.smallworldlabs.com\/sessions\/item\/54\/332\">una mesa redonda<\/a>sobre Transici\u00f3n a lo org\u00e1nico: c\u00f3mo las marcas y las organizaciones pueden apoyar el \u00e9xito de los agricultores.\u00a0<\/p>\n<p>La Subsecretaria del USDA Jenny Lester Moffitt, junto con el Director General de Daily Harvest Ricky Silver, Ryan Laur de American Farmland Trust, y Jessy Beckett Parr de CCOF hablar\u00e1n sobre estrategias creativas para apoyar los esfuerzos de transici\u00f3n org\u00e1nica con \u00e9xito a trav\u00e9s de asociaciones p\u00fablicas y privadas.\u00a0\u00a0<\/p>\n<p>El USDA, Daily Harvest, American Farmland Trust y CCOF crean programas que apoyan la transici\u00f3n de los agricultores a la agricultura org\u00e1nica con apoyo financiero directo, asistencia t\u00e9cnica 1:1, apoyo al acceso al mercado y tutor\u00eda.\u00a0<\/p>\n<p><strong>\u00danase a nosotros el jueves de 12.45 a 13.30 horas en el Anaheim Marriott, Grand Ballroom E.\u00a0<\/strong><\/p>\n<p><strong>Nos vemos en Anaheim.\u00a0<\/strong><\/p>\n<figure class=\"content-image\"><\/figure>","protected":false},"excerpt":{"rendered":"<p>\u00bfVa a asistir a la Natural Products Expo West?  \u00danase al CCOF en una mesa redonda sobre la transici\u00f3n ...<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[1],"class_list":["post-34051","post","type-post","status-publish","format-standard","hentry","category-uncategorized","language-english"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Join USDA Undersecretary Jenny Lester Moffitt and CCOF at Expo West - CCOF.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ccof.org\/es\/news\/join-usda-undersecretary-jenny-lester-moffitt-and-ccof-at-expo-west\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Join USDA Undersecretary Jenny Lester Moffitt and CCOF at Expo West - CCOF.org\" \/>\n<meta property=\"og:description\" content=\"Headed to Natural Products Expo West?\u00a0 Join CCOF for a panel discussion\u202fabout Transition &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ccof.org\/es\/news\/join-usda-undersecretary-jenny-lester-moffitt-and-ccof-at-expo-west\/\" \/>\n<meta property=\"og:site_name\" content=\"CCOF.org\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CCOForganic\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-08T17:16:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-23T21:10:02+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/news\\\/join-usda-undersecretary-jenny-lester-moffitt-and-ccof-at-expo-west\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/news\\\/join-usda-undersecretary-jenny-lester-moffitt-and-ccof-at-expo-west\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/person\\\/5ccd134e7ab95678db6afcb521a44e07\"},\"headline\":\"Join USDA Undersecretary Jenny Lester Moffitt and CCOF at Expo West\",\"datePublished\":\"2024-03-08T17:16:55+00:00\",\"dateModified\":\"2024-04-23T21:10:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/news\\\/join-usda-undersecretary-jenny-lester-moffitt-and-ccof-at-expo-west\\\/\"},\"wordCount\":122,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ccof.org\\\/news\\\/join-usda-undersecretary-jenny-lester-moffitt-and-ccof-at-expo-west\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/news\\\/join-usda-undersecretary-jenny-lester-moffitt-and-ccof-at-expo-west\\\/\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/news\\\/join-usda-undersecretary-jenny-lester-moffitt-and-ccof-at-expo-west\\\/\",\"name\":\"Join USDA Undersecretary Jenny Lester Moffitt and CCOF at Expo West - CCOF.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#website\"},\"datePublished\":\"2024-03-08T17:16:55+00:00\",\"dateModified\":\"2024-04-23T21:10:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/news\\\/join-usda-undersecretary-jenny-lester-moffitt-and-ccof-at-expo-west\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ccof.org\\\/news\\\/join-usda-undersecretary-jenny-lester-moffitt-and-ccof-at-expo-west\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/news\\\/join-usda-undersecretary-jenny-lester-moffitt-and-ccof-at-expo-west\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ccof.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Join USDA Undersecretary Jenny Lester Moffitt and CCOF at Expo West\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#website\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/\",\"name\":\"CCOF.org\",\"description\":\"Help make organic the norm!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ccof.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#organization\",\"name\":\"CCOF.org\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ccof.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/ccof-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.ccof.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/ccof-logo.svg\",\"width\":85,\"height\":111,\"caption\":\"CCOF.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CCOForganic\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CCOForganic\",\"https:\\\/\\\/www.instagram.com\\\/ccoforganic\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ccof.org\\\/#\\\/schema\\\/person\\\/5ccd134e7ab95678db6afcb521a44e07\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/www.ccof.org\\\/wp\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00danase a la Subsecretaria del USDA Jenny Lester Moffitt y al CCOF en Expo West - CCOF.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ccof.org\/es\/news\/join-usda-undersecretary-jenny-lester-moffitt-and-ccof-at-expo-west\/","og_locale":"es_MX","og_type":"article","og_title":"Join USDA Undersecretary Jenny Lester Moffitt and CCOF at Expo West - CCOF.org","og_description":"Headed to Natural Products Expo West?\u00a0 Join CCOF for a panel discussion\u202fabout Transition &hellip;","og_url":"https:\/\/www.ccof.org\/es\/news\/join-usda-undersecretary-jenny-lester-moffitt-and-ccof-at-expo-west\/","og_site_name":"CCOF.org","article_publisher":"https:\/\/www.facebook.com\/CCOForganic","article_published_time":"2024-03-08T17:16:55+00:00","article_modified_time":"2024-04-23T21:10:02+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ccof.org\/news\/join-usda-undersecretary-jenny-lester-moffitt-and-ccof-at-expo-west\/#article","isPartOf":{"@id":"https:\/\/www.ccof.org\/news\/join-usda-undersecretary-jenny-lester-moffitt-and-ccof-at-expo-west\/"},"author":{"name":"admin","@id":"https:\/\/www.ccof.org\/#\/schema\/person\/5ccd134e7ab95678db6afcb521a44e07"},"headline":"Join USDA Undersecretary Jenny Lester Moffitt and CCOF at Expo West","datePublished":"2024-03-08T17:16:55+00:00","dateModified":"2024-04-23T21:10:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ccof.org\/news\/join-usda-undersecretary-jenny-lester-moffitt-and-ccof-at-expo-west\/"},"wordCount":122,"commentCount":0,"publisher":{"@id":"https:\/\/www.ccof.org\/#organization"},"inLanguage":"es-MX","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ccof.org\/news\/join-usda-undersecretary-jenny-lester-moffitt-and-ccof-at-expo-west\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ccof.org\/news\/join-usda-undersecretary-jenny-lester-moffitt-and-ccof-at-expo-west\/","url":"https:\/\/www.ccof.org\/news\/join-usda-undersecretary-jenny-lester-moffitt-and-ccof-at-expo-west\/","name":"\u00danase a la Subsecretaria del USDA Jenny Lester Moffitt y al CCOF en Expo West - CCOF.org","isPartOf":{"@id":"https:\/\/www.ccof.org\/#website"},"datePublished":"2024-03-08T17:16:55+00:00","dateModified":"2024-04-23T21:10:02+00:00","breadcrumb":{"@id":"https:\/\/www.ccof.org\/news\/join-usda-undersecretary-jenny-lester-moffitt-and-ccof-at-expo-west\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ccof.org\/news\/join-usda-undersecretary-jenny-lester-moffitt-and-ccof-at-expo-west\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ccof.org\/news\/join-usda-undersecretary-jenny-lester-moffitt-and-ccof-at-expo-west\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ccof.org\/"},{"@type":"ListItem","position":2,"name":"Join USDA Undersecretary Jenny Lester Moffitt and CCOF at Expo West"}]},{"@type":"WebSite","@id":"https:\/\/www.ccof.org\/#website","url":"https:\/\/www.ccof.org\/","name":"CCOF.org","description":"\u00a1Ayude a que lo org\u00e1nico sea la norma!","publisher":{"@id":"https:\/\/www.ccof.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ccof.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.ccof.org\/#organization","name":"CCOF.org","url":"https:\/\/www.ccof.org\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.ccof.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.ccof.org\/wp-content\/uploads\/2024\/02\/ccof-logo.svg","contentUrl":"https:\/\/www.ccof.org\/wp-content\/uploads\/2024\/02\/ccof-logo.svg","width":85,"height":111,"caption":"CCOF.org"},"image":{"@id":"https:\/\/www.ccof.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CCOForganic","https:\/\/www.youtube.com\/c\/CCOForganic","https:\/\/www.instagram.com\/ccoforganic\/"]},{"@type":"Person","@id":"https:\/\/www.ccof.org\/#\/schema\/person\/5ccd134e7ab95678db6afcb521a44e07","name":"admin","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/www.ccof.org\/wp"]}]}},"_links":{"self":[{"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/posts\/34051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/comments?post=34051"}],"version-history":[{"count":2,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/posts\/34051\/revisions"}],"predecessor-version":[{"id":36750,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/posts\/34051\/revisions\/36750"}],"wp:attachment":[{"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/media?parent=34051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ccof.org\/es\/wp-json\/wp\/v2\/categories?post=34051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}